{"id":17457,"date":"2024-09-12T10:49:51","date_gmt":"2024-09-12T10:49:51","guid":{"rendered":"https:\/\/aludiecasting.com\/?p=17457"},"modified":"2024-09-13T17:10:19","modified_gmt":"2024-09-13T17:10:19","slug":"materiali-per-la-pressofusione-di-alluminio","status":"publish","type":"post","link":"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/","title":{"rendered":"Materiali per la pressofusione di alluminio: Guida completa"},"content":{"rendered":"<p>L'alluminio \u00e8 un materiale leggero. Offre un'eccellente resistenza alla corrosione. Per questo motivo, \u00e8 una scelta mirata in diversi settori industriali. \u00c8 disponibile con un'ampia gamma di leghe. Ogni lega di alluminio per pressofusione indica diversi attributi. Che variano dalla loro funzionalit\u00e0.<\/p>\n<p>La scelta del materiale adatto \u00e8 fondamentale. Facilita il processo di produzione. Inoltre, consente di ottenere il risultato desiderato.<\/p>\n<p>In questo articolo ne scopriremo le caratteristiche, i fattori di influenza e le applicazioni. Questo \u00e8 l'aspetto pi\u00f9 importante nella scelta del materiale appropriato.<\/p>\n<div id=\"attachment_16917\" style=\"width: 1120px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/06\/Cold-flow-section-with-plating-casting.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-16917\" class=\"size-full wp-image-16917\" src=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/06\/Cold-flow-section-with-plating-casting.jpg\" alt=\"materiale per la pressofusione di alluminio\" width=\"1110\" height=\"600\" title=\"\" srcset=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/06\/Cold-flow-section-with-plating-casting.jpg 1110w, https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/06\/Cold-flow-section-with-plating-casting-980x530.jpg 980w, https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/06\/Cold-flow-section-with-plating-casting-480x259.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1110px, 100vw\" \/><\/a><p id=\"caption-attachment-16917\" class=\"wp-caption-text\">Figura 7 Sezione di flusso a freddo con placcatura-fusione<\/p><\/div>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice dei contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Allinea la tabella dei contenuti\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #7c7c7c;color:#7c7c7c\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #7c7c7c;color:#7c7c7c\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Common_Aluminum_Die_Casting_Material_Alloys\" >Leghe comuni di alluminio per la pressofusione<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#A380_Aluminum_Alloy\" >Lega di alluminio A380<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Advantages\" >Vantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Disadvantages\" >Svantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#A356_Aluminum_Alloy\" >Lega di alluminio A356<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Advantages-2\" >Vantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Disadvantages-2\" >Svantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#A383_Aluminum_Alloy\" >Lega di alluminio A383<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Advantages-3\" >Vantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Disadvantages-3\" >Svantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#A413_Aluminum_Alloy\" >Lega di alluminio A413<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Advantages-4\" >Vantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Disadvantages-4\" >Svantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#A360_Aluminum_Alloy\" >Lega di alluminio A360<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Advantages-5\" >Vantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Disadvantages-5\" >Svantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Alloy_43\" >Lega 43<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Advantages-6\" >Vantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Disadvantages-6\" >Svantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#B390_Alloy\" >Lega B390<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Advantages-7\" >Vantaggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Disadvantages-7\" >Svantaggi<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Properties_of_Alloys_Impacting_the_Output_Result\" >Propriet\u00e0 delle leghe che influenzano il risultato di uscita<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Strength-to-Weight_Ratio\" >Rapporto forza-peso<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Corrosion_Resistance\" >Resistenza alla corrosione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Thermal_Conductivity\" >Conduttivit\u00e0 termica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Machinability\" >Lavorabilit\u00e0<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Properties_of_Alloys_Impacting_the_Casting_Process\" >Propriet\u00e0 delle leghe che influenzano il processo di colata<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Hot_Cracking\" >Cracking a caldo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Die_Soldering\" >Saldatura a stampo<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Factors_Influencing_Alloy_Selection_for_Die_Casting\" >Fattori che influenzano la selezione delle leghe per la pressofusione<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Mechanical_and_Physical_Properties\" >Propriet\u00e0 meccaniche e fisiche<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Fluidity\" >Fluidit\u00e0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Protection_from_Corrosion\" >Protezione dalla corrosione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-35\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Cost-effectiveness_and_manufacturing\" >Costo-efficacia e produzione<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-36\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Comprehensive_Comparison_of_Aluminum_Die-Casting_Alloys\" >Confronto completo delle leghe per pressofusione di alluminio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-37\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Applications_of_Aluminum_Alloys_in_Die_Casting\" >Applicazioni delle leghe di alluminio nella pressofusione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-38\" href=\"https:\/\/aludiecasting.com\/it\/materiali-per-la-pressofusione-di-alluminio\/#Conclusion\" >Conclusione:<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Common_Aluminum_Die_Casting_Material_Alloys\"><\/span>Leghe comuni di alluminio per la pressofusione<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Perch\u00e9 la scelta del materiale ha un impatto diretto sui processi di produzione o sui prodotti finali. Pertanto, \u00e8 necessario sceglierli con saggezza, soppesando i loro diversi attributi.<\/p>\n<p>Ogni <a href=\"https:\/\/en.wikipedia.org\/wiki\/Aluminium\" target=\"_blank\" rel=\"noopener\">lega di alluminio<\/a> fornisce determinate propriet\u00e0. Questo pu\u00f2 essere incline a prodotti specifici o un po' meno incline ad altri.<\/p>\n<p>Scoprite la composizione delle seguenti leghe. Sono comunemente utilizzate nella pressofusione ad alta pressione.<\/p>\n<ul>\n<li>Lega di alluminio A380<\/li>\n<li>Lega di alluminio A356<\/li>\n<li>Lega di alluminio A383<\/li>\n<li>Lega di alluminio A413<\/li>\n<li>Lega di alluminio A360<\/li>\n<li>Lega 43<\/li>\n<li>Lega B390<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"A380_Aluminum_Alloy\"><\/span>Lega di alluminio A380<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Il materiale \u00e8 una lega di alluminio 380. Viene utilizzata principalmente in diversi settori industriali. Contiene eccellenti qualit\u00e0 di resistenza alla corrosione. Questo materiale \u00e8 utilizzato specificamente per realizzare parti intricate con una geomatica resistente.<\/p>\n<p>Offre una grande resistenza meccanica e buone caratteristiche di trazione. Questa lega \u00e8 perfetta per produrre applicazioni di lunga durata. Esposta ad ambienti difficili.<\/p>\n<p>La sua resistenza non lo fa consumare rapidamente. Inoltre, i produttori possono facilmente lavorare, saldare o riparare questo materiale rispetto ad altri.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Advantages\"><\/span>Vantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Offrono eccellenti propriet\u00e0 di resistenza alla corrosione, soprattutto per applicazioni esterne, come coperture e rivestimenti.<\/li>\n<li>La sua durata \u00e8 sufficientemente efficiente da resistere a temperature operative estreme.<\/li>\n<li>Pu\u00f2 essere utilizzato per prodotti leggeri per migliorare la funzionalit\u00e0.<\/li>\n<li>La fluidit\u00e0 della lega A380 contribuisce a produrre forme complesse e pareti pi\u00f9 sottili.<\/li>\n<li>Offre un'efficace lavorabilit\u00e0.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Disadvantages\"><\/span>Svantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Costoso e difficile da riciclare<\/li>\n<li>Hanno una fusione pi\u00f9 bassa e non sono adatti a prodotti con carichi pesanti.<\/li>\n<li>Spesso provoca fessurazioni a caldo e porosit\u00e0.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"A356_Aluminum_Alloy\"><\/span>Lega di alluminio A356<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La lega di alluminio 356 \u00e8 ottimale per l'impiego nei settori aerospaziale e industriale. Con una buona resistenza alla trazione, offre una buona combinazione di componenti.<\/p>\n<p>Inoltre, presenta eccellenti caratteristiche di resistenza alla corrosione e di colabilit\u00e0. Questo lo rende una scelta adatta per la creazione di prodotti durevoli.<\/p>\n<p>Questo materiale \u00e8 facilmente reperibile. \u00c8 il materiale preferito in caso di prestazioni e riduzione del peso.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Advantages-2\"><\/span>Vantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Possiede un'elevata resistenza. \u00c8 adatto per applicazioni con carichi pesanti.<\/li>\n<li>La lega A356 presenta caratteristiche di saldabilit\u00e0 adeguate.<\/li>\n<li>Propone un'eccellente elasticit\u00e0 senza perdita di resistenza.<\/li>\n<li>Le sue caratteristiche di elevata durata e resistenza consentono di ottenere una qualit\u00e0 di resistenza all'usura.<\/li>\n<li>Offre un'eccellente fluidit\u00e0 per la colata.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Disadvantages-2\"><\/span>Svantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Questo materiale \u00e8 costoso e provoca una tonalit\u00e0 pi\u00f9 scura dell'alluminio durante l'anodizzazione.<\/li>\n<li>La sua conducibilit\u00e0 elettrica si riduce con l'invecchiamento naturale delle propriet\u00e0 del calore.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"A383_Aluminum_Alloy\"><\/span>Lega di alluminio A383<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>L'alluminio 383 \u00e8 un grado impressionante. \u00c8 utilizzato specificamente per la produzione di pezzi complessi con forme di precisione. Il produttore pu\u00f2 riempire gli stampi con un A380. \u00c8 leggermente migliore dell'A380.<\/p>\n<p>Essendo un buon conduttore di calore, offre un'eccellente resistenza alle alte temperature. Questa lega non si rompe in ambienti difficili. Tuttavia, i consumatori l'hanno trovata costosa e meno durevole dell'A380 e dell'A356.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Advantages-3\"><\/span>Vantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Si tratta di un materiale leggero.<\/li>\n<li>Presenta una maggiore resistenza alla corrosione.<\/li>\n<li>La lega A383 presenta una maggiore resistenza all'ossidazione.<\/li>\n<li>\u00c8 adatto a progetti di pressofusione complessi.<\/li>\n<li>Questo materiale \u00e8 economico e facile da colare.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Disadvantages-3\"><\/span>Svantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u00c8 meno resistente delle 380 leghe di alluminio.<\/li>\n<li>Talvolta provoca fragilit\u00e0, con raffreddamento rapido e fessurazione.<\/li>\n<li>Questa lega offre prestazioni limitate alle alte temperature.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"A413_Aluminum_Alloy\"><\/span>Lega di alluminio A413<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La lega A413 \u00e8 preferita per la sua tenuta ad alta resistenza. Con questa lega si possono produrre applicazioni come i componenti idraulici. Fornisce efficacemente uno scudo di resistenza alle perdite a tutti i prodotti.<\/p>\n<p>Questo materiale offre anche una buona resistenza alla corrosione per l'applicazione. Questo comporta la dissipazione del calore.  Risponde molto bene ai parametri di pressofusione.<\/p>\n<p>La lega A413 offre un'eccellente lavorabilit\u00e0 e un ottimo rapporto resistenza\/peso. Per questo motivo, i diecaster la scelgono per i loro progetti. Che necessitano di un'elevata resistenza.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Advantages-4\"><\/span>Vantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Questa lega \u00e8 in grado di resistere alle alte pressioni senza subire rotture e flessioni.<\/li>\n<li>Presenta caratteristiche di elevato rapporto resistenza\/peso.<\/li>\n<li>A413 offre resistenza alle cricche a caldo.<\/li>\n<li>\u00c8 il materiale migliore per la fusione di forme geometriche complesse.<\/li>\n<li>Offre una fluidit\u00e0 superiore e un'equilibrata conduzione e aspetti termici.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Disadvantages-4\"><\/span>Svantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u00c8 costosa rispetto alla lega A383.<\/li>\n<li>Questo materiale non conserva la purezza.<\/li>\n<li>Ha una resistenza alla trazione inferiore rispetto agli altri.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"A360_Aluminum_Alloy\"><\/span>Lega di alluminio A360<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le eccellenti caratteristiche di duttilit\u00e0, forza e resistenza alla corrosione della lega di alluminio A360 la distinguono da altri materiali. \u00c8 efficace per produrre pezzi con una fluidit\u00e0 e una tenuta alla pressione sorprendenti. Ci\u00f2 attrae molti stampatori.<\/p>\n<p>Presenta una tenuta alla pressione superiore rispetto alla lega di alluminio A380. Inoltre, presenta una grande fluidit\u00e0 durante la colata. Questo facilita il processo di stampaggio. Per questo motivo, i fonditori possono produrre pezzi con forme dettagliate.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Advantages-5\"><\/span>Vantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Permette processi di fusione ad alta precisione.<\/li>\n<li>Questa lega possiede eccellenti caratteristiche di duttilit\u00e0 e resistenza alla corrosione.<\/li>\n<li>Fornisce stabilit\u00e0 dimensionale.<\/li>\n<li>I produttori possono adottare questa lega quando \u00e8 richiesta un'elevata resistenza meccanica alle alte temperature.<\/li>\n<li>Inoltre, offre lavorabilit\u00e0 e durata per l'industria automobilistica e aeronautica.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Disadvantages-5\"><\/span>Svantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u00c8 pi\u00f9 costoso dell'acciaio.<\/li>\n<li>Richiede finiture superficiali e si graffia facilmente.<\/li>\n<li>Questa lega non \u00e8 facile da fondere.<\/li>\n<li>Non si illumina di rosso prima di raggiungere la temperatura di riscaldamento.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Alloy_43\"><\/span>Lega 43<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La lega 43 non \u00e8 facilmente reperibile. In un certo senso, questo materiale non \u00e8 comunemente utilizzato nella produzione a causa della sua moderata resistenza alla corrosione. Tuttavia, offre un'elevata flessibilit\u00e0 ed \u00e8 adatto alla produzione di prodotti marini.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Advantages-6\"><\/span>Vantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Fornire i requisiti di flessibilit\u00e0.<\/li>\n<li>Possiede una buona forza<\/li>\n<li>\u00c8 conveniente e facilmente disponibile.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Disadvantages-6\"><\/span>Svantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u00c8 difficile lavorare a macchina<\/li>\n<li>Questo materiale pu\u00f2 essere fragile e causare crepe.<\/li>\n<li>La resistenza alla corrosione \u00e8 limitata.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"B390_Alloy\"><\/span>Lega B390<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Se state per produrre prodotti con un'elevata capacit\u00e0 portante, dovete scegliere la lega B390. Questo materiale \u00e8 preferibile per la creazione di pistoni, pompe e sistemi frenanti. Richiede resistenza all'usura.<\/p>\n<p>Tuttavia, provoca difficolt\u00e0 durante la lavorazione e aggressivit\u00e0 sugli utensili per la pressofusione.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Advantages-7\"><\/span>Vantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Ha punti di fusione pi\u00f9 bassi rispetto ad altri.<\/li>\n<li>Forniscono duttilit\u00e0 e propriet\u00e0 rigide.<\/li>\n<li>Offre una notevole conduttivit\u00e0.<\/li>\n<li>Questa lega contiene caratteristiche di alto riciclo e fluidit\u00e0 di colata.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Disadvantages-7\"><\/span>Svantaggi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>\u00c8 pi\u00f9 difficile anodizzare<\/li>\n<li>Presenta una minore duttilit\u00e0<\/li>\n<li>Propriet\u00e0 meccaniche e di resistenza alla corrosione inferiori<\/li>\n<li>Richiede procedure di manipolazione sicure.<\/li>\n<li>Pu\u00f2 causare l'usura della cavit\u00e0 dello stampo e dei forni di fusione a temperature elevate.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Properties_of_Alloys_Impacting_the_Output_Result\"><\/span>Propriet\u00e0 delle leghe che influenzano il risultato di uscita<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u00c8 necessario conoscere le diverse caratteristiche e le sfide delle leghe. Questo vi aiuter\u00e0 a determinare il materiale necessario per i vostri progetti.<\/p>\n<p>Inoltre, la scelta di materiali sbagliati pu\u00f2 creare difetti nei prodotti finali. Ad esempio, perdite, forme inadeguate o scarsa funzionalit\u00e0.<\/p>\n<p>Di seguito \u00e8 riportata una caratteristica comune delle leghe di alluminio. Che possono avere un impatto sulla produzione.<\/p>\n<ul>\n<li>Rapporto forza-peso<\/li>\n<li>Resistenza alla corrosione<\/li>\n<li>Conduttivit\u00e0 termica<\/li>\n<li>Lavorabilit\u00e0<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Strength-to-Weight_Ratio\"><\/span>Rapporto forza-peso<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le diverse leghe di alluminio sono essenziali in ogni settore, in quanto offrono un eccellente rapporto resistenza-peso. La leggerezza delle leghe di alluminio pu\u00f2 migliorare la funzionalit\u00e0 delle applicazioni e ridurre il consumo di carburante. Questa considerazione \u00e8 efficace per la produzione di particolari applicazioni in cui il peso \u00e8 una preoccupazione.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Corrosion_Resistance\"><\/span>Resistenza alla corrosione<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le leghe di alluminio sono altamente preferibili per resistere alla corrosione.  Il materiale produce strati protettivi di ossido sulla superficie. Ci\u00f2 contribuisce a ridurre la ruggine e il degrado in situazioni difficili.<\/p>\n<p>Diverse applicazioni, soprattutto negli edifici, nelle abitazioni e nel settore automobilistico, comportano l'esposizione all'umidit\u00e0. Pertanto, i produttori possono garantire la longevit\u00e0 di questi componenti. A tal fine, possono scegliere leghe con eccellenti caratteristiche di resistenza alla corrosione. Ad esempio, una 380 o una 356.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Thermal_Conductivity\"><\/span>Conduttivit\u00e0 termica<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le leghe di alluminio offrono una conduttivit\u00e0 termica indispensabile. Ci\u00f2 \u00e8 vantaggioso per produrre i pezzi gestendo il calore senza rischiare la resistenza. Scegliete il materiale che offre una buona conducibilit\u00e0 termica per i vostri progetti. Ad esempio, nelle applicazioni ad alta temperatura come i dissipatori di calore e i sistemi motore.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Machinability\"><\/span>Lavorabilit\u00e0<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le diverse leghe di alluminio funzionano in modo diverso se esposte a processi di pressofusione o addirittura di foratura. Alcune sono difficili da lavorare, altre rendono il lavoro impeccabile. Scegliete quindi la lega che si piega facilmente nello stampo per creare forme complesse.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Properties_of_Alloys_Impacting_the_Casting_Process\"><\/span>Propriet\u00e0 delle leghe che influenzano il processo di colata<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/aluminum-die-casting.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17459 size-large\" src=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/aluminum-die-casting-1024x769.jpg\" alt=\"difetti della pressofusione di alluminio\" width=\"1024\" height=\"769\" title=\"\" srcset=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/aluminum-die-casting-1024x769.jpg 1024w, https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/aluminum-die-casting-980x736.jpg 980w, https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/aluminum-die-casting-480x361.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p>Anche il materiale preferito per la colata pu\u00f2 influire sul processo in diversi modi. Pu\u00f2 causare problemi durante la produzione.<\/p>\n<ul>\n<li>Cracking a caldo<\/li>\n<li>Saldatura a stampo<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Hot_Cracking\"><\/span>Cracking a caldo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La cricca a caldo nel processo di pressofusione si riferisce anche alla cricca da saldatura. \u00c8 un difetto tipico delle leghe di alluminio. Pu\u00f2 provocare lacerazioni interne o superficiali. Le leghe che sono soggette a sollecitazioni interne indotte dal calore causano spesso difetti.  Questi materiali sono pi\u00f9 suscettibili di altri alla criccatura a caldo. Tuttavia, le leghe con una maggiore duttilit\u00e0, come la 360, aiutano a ridurre le cricche a caldo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Die_Soldering\"><\/span>Saldatura a stampo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La saldatura in stampo \u00e8 un altro difetto che si verifica durante il processo di pressofusione. Le leghe si attaccano alla parete dello stampo e ostacolano il processo di espulsione. Questo danneggia gravemente la fusione e gli stampi. Pertanto, \u00e8 necessario cercare una lega che contenga caratteristiche anti-saldatura.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Factors_Influencing_Alloy_Selection_for_Die_Casting\"><\/span>Fattori che influenzano la selezione delle leghe per la pressofusione<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il processo di produzione perfetto inizia con la scelta del materiale, soppesando le sue propriet\u00e0 distintive. Alcune applicazioni sono soggette a una costante flessibilit\u00e0. Per questo motivo, prima di scegliere la lega, \u00e8 bene considerare i seguenti aspetti:<\/p>\n<ul>\n<li>Propriet\u00e0 meccaniche e fisiche<\/li>\n<li>Fluidit\u00e0<\/li>\n<li>Protezione dalla corrosione<\/li>\n<li>Costo-efficacia e produzione<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Mechanical_and_Physical_Properties\"><\/span>Propriet\u00e0 meccaniche e fisiche<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Considerare le caratteristiche meccaniche e fisiche del materiale. Si tratta di resistenza, durezza, duttilit\u00e0, ecc. Queste caratteristiche definiscono la lavorabilit\u00e0 delle leghe sotto sforzo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Fluidity\"><\/span>Fluidit\u00e0<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><a href=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/fludity-in-aluminum-die-casting.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17460 size-large\" src=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/fludity-in-aluminum-die-casting-1024x438.jpg\" alt=\"fludit\u00e0 alluminio pressofuso\" width=\"1024\" height=\"438\" title=\"\" srcset=\"https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/fludity-in-aluminum-die-casting-980x419.jpg 980w, https:\/\/aludiecasting.com\/wp-content\/uploads\/2024\/09\/fludity-in-aluminum-die-casting-480x205.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p>L'elevata fluidit\u00e0 \u00e8 necessaria per le applicazioni in cui la precisione \u00e8 fondamentale. \u00c8 un altro aspetto cruciale. La lega selezionata deve scorrere bene nello stampo. In modo che possa riempire forme complesse senza difetti. Questo aspetto \u00e8 fondamentale per la produzione di pezzi con forme dettagliate e disegni intricati.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Protection_from_Corrosion\"><\/span>Protezione dalla corrosione<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le leghe di alluminio con un'eccellente capacit\u00e0 di resistenza alla corrosione hanno una durata di vita pi\u00f9 lunga. Riduce i costi di riparazione e manutenzione.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Cost-effectiveness_and_manufacturing\"><\/span>Costo-efficacia e produzione<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Il costo del metallo influenza in modo significativo il processo di produzione e il budget complessivo. Queste sono le considerazioni pratiche. Allo stesso modo, processi di produzione efficienti influiscono sul costo totale di produzione. Ci\u00f2 pu\u00f2 includere anche il tempo di ciclo e le percentuali di scarto.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comprehensive_Comparison_of_Aluminum_Die-Casting_Alloys\"><\/span>Confronto completo delle leghe per pressofusione di alluminio<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ecco un confronto completo delle leghe di alluminio per pressofusione. In questo modo si avr\u00e0 un quadro chiaro delle differenze tra le loro propriet\u00e0.<\/p>\n<table width=\"600\">\n<tbody>\n<tr>\n<td width=\"103\"><strong>Propriet\u00e0<\/strong><\/td>\n<td width=\"74\"><strong>Lega A380<\/strong><\/td>\n<td width=\"71\"><strong>Lega A356<\/strong><\/td>\n<td width=\"68\"><strong>Lega A383<\/strong><\/td>\n<td width=\"71\"><strong>Lega A413<\/strong><\/td>\n<td width=\"71\"><strong>Lega A360<\/strong><\/td>\n<td width=\"70\"><strong>Lega 43<\/strong><\/td>\n<td width=\"72\"><strong>Lega B390<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Densit\u00e0 (g\/cm\u00b3)<\/strong><\/td>\n<td width=\"74\">2.71<\/td>\n<td width=\"71\">2.68<\/td>\n<td width=\"68\">2.74<\/td>\n<td width=\"71\">2.66<\/td>\n<td width=\"71\">2.63<\/td>\n<td width=\"70\">2.80<\/td>\n<td width=\"72\">2.80<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Intervallo di fusione (\u00b0C)<\/strong><\/td>\n<td width=\"74\">540-595<\/td>\n<td width=\"71\">555-615<\/td>\n<td width=\"68\">516-582<\/td>\n<td width=\"71\">573-613<\/td>\n<td width=\"71\">557-596<\/td>\n<td width=\"70\">525-595<\/td>\n<td width=\"72\">510-595<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Conduttivit\u00e0 elettrica (% IACS)<\/strong><\/td>\n<td width=\"74\">27<\/td>\n<td width=\"71\">36<\/td>\n<td width=\"68\">23<\/td>\n<td width=\"71\">35<\/td>\n<td width=\"71\">30<\/td>\n<td width=\"70\">21<\/td>\n<td width=\"72\">22<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Conduttivit\u00e0 termica (W\/m-K)<\/strong><\/td>\n<td width=\"74\">96.2<\/td>\n<td width=\"71\">110<\/td>\n<td width=\"68\">96.2<\/td>\n<td width=\"71\">117<\/td>\n<td width=\"71\">113<\/td>\n<td width=\"70\">92<\/td>\n<td width=\"72\">109<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Resistenza alla trazione finale (MPa)<\/strong><\/td>\n<td width=\"74\">320<\/td>\n<td width=\"71\">250<\/td>\n<td width=\"68\">310<\/td>\n<td width=\"71\">320<\/td>\n<td width=\"71\">320<\/td>\n<td width=\"70\">300<\/td>\n<td width=\"72\">390<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Resistenza allo snervamento (MPa)<\/strong><\/td>\n<td width=\"74\">160<\/td>\n<td width=\"71\">175<\/td>\n<td width=\"68\">150<\/td>\n<td width=\"71\">160<\/td>\n<td width=\"71\">170<\/td>\n<td width=\"70\">140<\/td>\n<td width=\"72\">250<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Durezza (BHN)<\/strong><\/td>\n<td width=\"74\">80<\/td>\n<td width=\"71\">65<\/td>\n<td width=\"68\">75<\/td>\n<td width=\"71\">75<\/td>\n<td width=\"71\">75<\/td>\n<td width=\"70\">70<\/td>\n<td width=\"72\">90<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Resistenza alla fatica (MPa)<\/strong><\/td>\n<td width=\"74\">140<\/td>\n<td width=\"71\">95<\/td>\n<td width=\"68\">145<\/td>\n<td width=\"71\">95<\/td>\n<td width=\"71\">120<\/td>\n<td width=\"70\">120<\/td>\n<td width=\"72\">125<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Resistenza al taglio (MPa)<\/strong><\/td>\n<td width=\"74\">190<\/td>\n<td width=\"71\">150<\/td>\n<td width=\"68\">190<\/td>\n<td width=\"71\">180<\/td>\n<td width=\"71\">180<\/td>\n<td width=\"70\">185<\/td>\n<td width=\"72\">210<\/td>\n<\/tr>\n<tr>\n<td width=\"103\"><strong>Allungamento (%)<\/strong><\/td>\n<td width=\"74\">3.5<\/td>\n<td width=\"71\">7.0<\/td>\n<td width=\"68\">3.5<\/td>\n<td width=\"71\">3.5<\/td>\n<td width=\"71\">3.5<\/td>\n<td width=\"70\">3.0<\/td>\n<td width=\"72\">1.0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2><span class=\"ez-toc-section\" id=\"Applications_of_Aluminum_Alloys_in_Die_Casting\"><\/span>Applicazioni delle leghe di alluminio nella pressofusione<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>I materiali a base di alluminio sono ampiamente utilizzati in numerosi settori industriali. La loro leggerezza e l'alta resistenza sono vantaggiose per le parti critiche. Nelle applicazioni strutturali offrono resistenza e risparmio di carburante. Ecco alcune applicazioni di queste leghe. Queste sono menzionate nella tabella seguente:<\/p>\n<table width=\"602\">\n<tbody>\n<tr>\n<td width=\"150\"><strong>Lega<\/strong><\/td>\n<td width=\"150\"><strong>Propriet\u00e0 chiave<\/strong><\/td>\n<td width=\"150\"><strong>Applicazioni<\/strong><\/td>\n<td width=\"150\"><strong>Industrie<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"150\"><strong>Lega A380<\/strong><\/td>\n<td width=\"150\">Buone propriet\u00e0 meccaniche, tenuta alla pressione<\/td>\n<td width=\"150\">Blocchi motore, scatole di trasmissione, cambi<\/td>\n<td width=\"150\">Industria automobilistica<\/td>\n<\/tr>\n<tr>\n<td width=\"150\"><strong>Lega A360<\/strong><\/td>\n<td width=\"150\">Elevata resistenza alla corrosione, tenuta alla pressione<\/td>\n<td width=\"150\">Componenti strutturali, involucri, coperture del motore<\/td>\n<td width=\"150\">Automotive, attrezzature industriali<\/td>\n<\/tr>\n<tr>\n<td width=\"150\"><strong>Lega A356<\/strong><\/td>\n<td width=\"150\">Flessibilit\u00e0 superiore, rapporto resistenza\/peso<\/td>\n<td width=\"150\">Telaio, ruote, parti strutturali<\/td>\n<td width=\"150\">Automotive, macchinari industriali<\/td>\n<\/tr>\n<tr>\n<td width=\"150\"><strong>Lega A383<\/strong><\/td>\n<td width=\"150\">Stabilit\u00e0 dimensionale, colabilit\u00e0<\/td>\n<td width=\"150\">Custodie, alloggiamenti e connettori elettronici<\/td>\n<td width=\"150\">Elettronica, beni di consumo<\/td>\n<\/tr>\n<tr>\n<td width=\"150\"><strong>Lega A413<\/strong><\/td>\n<td width=\"150\">Elevata conducibilit\u00e0 termica, tenuta alla pressione<\/td>\n<td width=\"150\">Dissipatori di calore, componenti idraulici, coperture del motore<\/td>\n<td width=\"150\">Elettronica, automotive<\/td>\n<\/tr>\n<tr>\n<td width=\"150\"><strong>Lega 43<\/strong><\/td>\n<td width=\"150\">Buona resistenza alla corrosione, forza moderata<\/td>\n<td width=\"150\">Attrezzature per esterni, parti strutturali, elettronica di consumo<\/td>\n<td width=\"150\">Attrezzature industriali, beni di consumo<\/td>\n<\/tr>\n<tr>\n<td width=\"150\"><strong>Lega B390<\/strong><\/td>\n<td width=\"150\">Eccellente resistenza all'usura, bassa elasticit\u00e0<\/td>\n<td width=\"150\">Parti di motore ad alte prestazioni, componenti della trasmissione, dissipatori di calore<\/td>\n<td width=\"150\">Automotive, elettronica, attrezzature industriali<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusione:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le leghe di alluminio offrono un'ampia gamma di utilit\u00e0 in diversi settori. Offrono caratteristiche distintive. Ognuna di esse \u00e8 fondamentale per soddisfare le specifiche dei componenti richiesti. La determinazione dei materiali si basa in modo significativo sulle loro caratteristiche. Pertanto, comprenderle a fondo pu\u00f2 aiutare il <a href=\"https:\/\/aludiecasting.com\/it\/pressofusione-di-alluminio-2\/\">diecaster in alluminio<\/a>. Li guida nel procedere con l'acquisizione del materiale.<\/p>","protected":false},"excerpt":{"rendered":"<p>La pressofusione di alluminio permette di realizzare parti metalliche complesse e di alta qualit\u00e0. Scoprite le diverse leghe di alluminio comunemente utilizzate nella pressofusione, le loro propriet\u00e0 e le loro applicazioni. <\/p>","protected":false},"author":2,"featured_media":17458,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-17457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aluminium-die-casting"],"_links":{"self":[{"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/posts\/17457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/comments?post=17457"}],"version-history":[{"count":0,"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/posts\/17457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/media\/17458"}],"wp:attachment":[{"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/media?parent=17457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/categories?post=17457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aludiecasting.com\/it\/wp-json\/wp\/v2\/tags?post=17457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}