{"id":17651,"date":"2024-11-24T09:03:34","date_gmt":"2024-11-24T09:03:34","guid":{"rendered":"https:\/\/www.aludiecasting.com\/?p=17651"},"modified":"2024-11-24T09:03:37","modified_gmt":"2024-11-24T09:03:37","slug":"latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes","status":"publish","type":"post","link":"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/","title":{"rendered":"Lat\u00e3o x Bronze x Cobre: Diferen\u00e7as b\u00e1sicas e aplica\u00e7\u00f5es"},"content":{"rendered":"<p>H\u00e1 tr\u00eas diferen\u00e7as b\u00e1sicas entre lat\u00e3o, bronze e cobre. O cobre \u00e9 um metal puro. Lat\u00e3o e bronze s\u00e3o ligas. O lat\u00e3o \u00e9 uma liga de cobre. O bronze \u00e9 uma liga de cobre e estanho.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Propriedade<\/strong><\/td><td><strong>Cobre<\/strong><\/td><td><em>Lat\u00e3o<\/em><\/td><td><strong>Bronze<\/strong><\/td><\/tr><tr><td>Composi\u00e7\u00e3o<\/td><td>Cobre puro<\/td><td>Cobre + Zinco<\/td><td>Cobre + Estanho<\/td><\/tr><tr><td>Cor<\/td><td>Marrom avermelhado<\/td><td>Amarelo dourado<\/td><td>De marrom escuro a dourado<\/td><\/tr><tr><td>**Densidade (g\/cm\u00b3)<\/td><td>8.96<\/td><td>8.4-8.73<\/td><td>7.4-8.9<\/td><\/tr><tr><td>Ponto de fus\u00e3o (\u00b0C)<\/td><td>1085<\/td><td>900-940<\/td><td>950-1050<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Vamos comparar suas propriedades, usos, pr\u00f3s e contras e aplica\u00e7\u00f5es. Assim, voc\u00ea poder\u00e1 identific\u00e1-los e escolher o metal certo para o seu projeto.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #7c7c7c;color:#7c7c7c\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #7c7c7c;color:#7c7c7c\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#What_are_Copper_Brass_and_Bronze\" >O que s\u00e3o cobre, lat\u00e3o e bronze?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Copper\" >Cobre:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Pros_of_Copper\" >Pr\u00f3s do cobre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Cons_of_Copper\" >Contras do cobre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Brass\" >Lat\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Pros_of_Brass\" >Pr\u00f3s do lat\u00e3o:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Cons_of_Brass\" >Contras do lat\u00e3o:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Bronze_Built_for_Durability\" >Bronze: Constru\u00eddo para durar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Pros_of_Bronze\" >Pr\u00f3s do Bronze:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Cons_of_Bronze\" >Contras do Bronze:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Difference_Between_Copper_Brass_and_Bronze%E2%80%8B\" >Diferen\u00e7a entre cobre, lat\u00e3o e bronze<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Grades_of_Copper_Brass_and_Bronze\" >Graus de cobre, lat\u00e3o e bronze<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Copper_Alloy_Grades_and_Uses\" >Classes e usos de ligas de cobre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Brass_Alloy_Grades_and_Uses\" >Classes e usos de ligas de lat\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Bronze_Alloy_Grades_and_Uses\" >Classes e usos de ligas de bronze<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Applications_of_Copper_Brass_and_Bronze\" >Aplica\u00e7\u00f5es de cobre, lat\u00e3o e bronze<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#1_Electrical_Wiring\" >1.   Fia\u00e7\u00e3o el\u00e9trica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#2_Plumbing_Systems\" >2.   Sistemas de encanamento<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#3_Marine_Industry\" >3.   Setor mar\u00edtimo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#4_Decorative_Items_and_Statues\" >4.   Itens decorativos e est\u00e1tuas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#5_Musical_Instruments\" >5.   Instrumentos musicais<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Are_copper_brass_and_bronze_are_sustainable_metals\" >O cobre, o lat\u00e3o e o bronze s\u00e3o metais sustent\u00e1veis?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Sustainability_Benefits\" >Benef\u00edcios de sustentabilidade<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#How_to_identify_copper_or_bronze_or_brass\" >Como identificar cobre, bronze ou lat\u00e3o?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Color_Differences\" >Diferen\u00e7as de cor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Scratch_and_Density_Test\" >Teste de arranh\u00f5es e densidade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Magnetism\" >Magnetismo<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#Conclusion\" >Conclus\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/aludiecasting.com\/pt\/latao-vs-bronze-vs-cobre-diferencas-basicas-e-aplicacoes\/#FAQs\" >Perguntas frequentes<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"What_are_Copper_Brass_and_Bronze\"><\/span><a><\/a>O que s\u00e3o cobre, lat\u00e3o e bronze?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"A diferen\u00e7a entre cobre, lat\u00e3o e bronze\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/ysInnHOoouc?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Copper\"><\/span><a><\/a>Cobre:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/1b.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/1b-1024x1024.jpg\" alt=\"suti\u00e3s\" class=\"wp-image-17652\" title=\"\" srcset=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/1b-1024x1024.jpg 1024w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/1b-980x980.jpg 980w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/1b-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<p>O cobre \u00e9 um material puro e <a href=\"https:\/\/en.wikipedia.org\/wiki\/Native_metal\" target=\"_blank\" rel=\"noopener\">metal nativo<\/a>. \u00c9 um metal laranja-avermelhado com <a href=\"https:\/\/en.wikipedia.org\/wiki\/Tarnish\" target=\"_blank\" rel=\"noopener\">manchar<\/a>. Esse metal \u00e9 macio por natureza. Tem um n\u00famero at\u00f4mico de 29. O cobre re\u00fane a ductilidade, a condutividade t\u00e9rmica e a resist\u00eancia \u00e0 corros\u00e3o em uma \u00fanica pe\u00e7a de fabrica\u00e7\u00e3o.<\/p>\n\n\n\n<p>De fato, o cobre<a href=\"https:\/\/www.thoughtco.com\/copper-history-pt-i-2340112#:~:text=relatively%20pure%20forms.-,Copper%20Findings,extract%20and%20work%20with%20copper.\" target=\"_blank\" rel=\"noopener\"> foi totalmente descoberto e utilizado h\u00e1 cerca de 5000 a 6000 anos<\/a>. Com o tempo, os desenvolvedores descobriram que o <a href=\"https:\/\/en.wikipedia.org\/wiki\/Patina\" target=\"_blank\" rel=\"noopener\">p\u00e1tina<\/a> no cobre. Isso determina como suas aplica\u00e7\u00f5es lutam contra a oxida\u00e7\u00e3o adicional.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pros_of_Copper\"><\/span><a><\/a>Pr\u00f3s do cobre<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O cobre \u00e9 extremamente resiliente e resistente \u00e0 corros\u00e3o, oferecendo boa condutividade. Por isso, tem excelente maleabilidade para produzir fios e chapas d\u00facteis. Quando se trata de propriedades antimicrobianas para projetos higi\u00eanicos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cons_of_Copper\"><\/span><a><\/a>Contras do cobre<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Mais caro que o lat\u00e3o e o bronze, o cobre n\u00e3o \u00e9 adequado para pe\u00e7as de alto desempenho. Eles causam problemas de arranh\u00f5es e amassados. A maioria das superf\u00edcies de cobre geralmente precisa de tratamentos para remo\u00e7\u00e3o de manchas.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Brass\"><\/span>Lat\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/2b.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/2b-1024x1024.jpg\" alt=\"cobre\" class=\"wp-image-17653\" title=\"\" srcset=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/2b-1024x1024.jpg 1024w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/2b-980x980.jpg 980w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/2b-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<p>A composi\u00e7\u00e3o do lat\u00e3o varia muito, incluindo <a href=\"https:\/\/en.wikipedia.org\/wiki\/Brass#:~:text=Brass%20is%20an%20alloy%20of,%25%20copper%20and%2034%25%20zinc.\" target=\"_blank\" rel=\"noopener\">66% de cobre + 34% de zinco<\/a>. Eles geram uma tonalidade amarela p\u00e1lida brilhante de tirar o f\u00f4lego. A maior parte do lat\u00e3o tamb\u00e9m \u00e9 composta de outros elementos. Por exemplo, ars\u00eanico, chumbo, f\u00f3sforo, AL, mangan\u00eas e sil\u00edcio.<\/p>\n\n\n\n<p>As ligas de lat\u00e3o tendem a oferecer boa resist\u00eancia \u00e0 corros\u00e3o. Sua maleabilidade, for\u00e7a e versatilidade s\u00e3o as escolhas preferidas. Os antigos romanos usavam o lat\u00e3o para fabricar vasos, armaduras, joias e broches.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pros_of_Brass\"><\/span><a><\/a>Pr\u00f3s do lat\u00e3o:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O lat\u00e3o define as barreiras contra oxida\u00e7\u00e3o ou corros\u00e3o. Eles s\u00e3o confi\u00e1veis e melhoram a apar\u00eancia. A maleabilidade do lat\u00e3o converte facilmente a mat\u00e9ria-prima em projetos complexos. Esse metal resistente permite uma fabrica\u00e7\u00e3o mais r\u00e1pida e est\u00e1vel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cons_of_Brass\"><\/span><a><\/a>Contras do lat\u00e3o:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ao contr\u00e1rio do cobre, o lat\u00e3o tem baixa condutividade el\u00e9trica. Exigindo manuten\u00e7\u00e3o adequada, ele tamb\u00e9m gera manchas e rachaduras por corros\u00e3o sob tens\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Bronze_Built_for_Durability\"><\/span><a><\/a>Bronze: Constru\u00eddo para durar<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/3b.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/3b-1024x1024.jpg\" alt=\"\" class=\"wp-image-17654\" title=\"\" srcset=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/3b-1024x1024.jpg 1024w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/3b-980x980.jpg 980w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/3b-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<p>O bronze \u00e9 normalmente fabricado com <a href=\"https:\/\/www.britannica.com\/technology\/bronze-alloy\" target=\"_blank\" rel=\"noopener\">88% de cobre mais 12% de estanho<\/a>. Materiais como AL, zn ou estanho tamb\u00e9m s\u00e3o adicionados ao bronze, melhorando, assim, suas propriedades gerais. Esse metal tem cor marrom avermelhada, o que facilita a fabrica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m de sua resist\u00eancia, durabilidade e prote\u00e7\u00e3o contra ferrugem, o bronze \u00e9 um metal vers\u00e1til. Isso permite que ele desenvolva p\u00e1tina para se proteger da intemp\u00e9rie da melhor forma poss\u00edvel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pros_of_Bronze\"><\/span><a><\/a>Pr\u00f3s do Bronze:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Resist\u00eancia \u00e0 corros\u00e3o, durabilidade e baixo atrito s\u00e3o os atributos do bronze. Isso garante a funcionalidade adequada e evita danos \u00e0s pe\u00e7as.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cons_of_Bronze\"><\/span><a><\/a>Contras do Bronze:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O bronze \u00e9 mais fr\u00e1gil do que outras ligas. Ele produz rachaduras sob forte estresse. A presen\u00e7a de estanho no bronze o torna caro. Al\u00e9m disso, \u00e9 mais pesado que o lat\u00e3o e n\u00e3o \u00e9 adequado para pe\u00e7as leves.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Difference_Between_Copper_Brass_and_Bronze%E2%80%8B\"><\/span><a><\/a>Diferen\u00e7a entre cobre, lat\u00e3o e bronze<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/4b.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/4b-1024x1024.jpg\" alt=\"Diferen\u00e7a entre cobre, lat\u00e3o e bronze\" class=\"wp-image-17656\" title=\"\" srcset=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/4b-1024x1024.jpg 1024w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/4b-980x980.jpg 980w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/4b-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Grades_of_Copper_Brass_and_Bronze\"><\/span><a><\/a>Graus de cobre, lat\u00e3o e bronze<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Copper_Alloy_Grades_and_Uses\"><\/span><a><\/a>Classes e usos de ligas de cobre<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/5b.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/5b-1024x1024.jpg\" alt=\"\" class=\"wp-image-17657\" title=\"\" srcset=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/5b-1024x1024.jpg 1024w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/5b-980x980.jpg 980w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/5b-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Grau<\/strong><\/td><td><strong>Composi\u00e7\u00e3o<\/strong><\/td><td><strong>Usos comuns<\/strong><\/td><\/tr><tr><td><strong>C11000<\/strong><\/td><td>99,9 % Cobre puro<\/td><td>A fia\u00e7\u00e3o, o encanamento, o telhado e os trocadores de calor precisam ser fabricados de forma bastante elegante em termos de condutividade t\u00e9rmica e resist\u00eancia \u00e0 corros\u00e3o.<\/td><\/tr><tr><td><strong>C10200<\/strong><\/td><td>99,9% Cobre + 0,02% oxig\u00eanio<\/td><td>Ele garante alta formabilidade em dispositivos condutores de eletricidade.<\/td><\/tr><tr><td><strong>C12000<\/strong><\/td><td>99,9% Cobre + 0,01 a 0,03% F\u00f3sforo<\/td><td>Isso suaviza o desempenho dos cabos de energia e comunica\u00e7\u00e3o e dos conectores el\u00e9tricos.<\/td><\/tr><tr><td><strong>C14500<\/strong><\/td><td>99,9% Cobre + 0,1% Prata<\/td><td>Ele oferece prote\u00e7\u00e3o conveniente em contatos el\u00e9tricos e pain\u00e9is de distribui\u00e7\u00e3o de alto desempenho.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Brass_Alloy_Grades_and_Uses\"><\/span><a><\/a>Classes e usos de ligas de lat\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/7b.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/7b-1024x1024.jpg\" alt=\"v\u00e1lvula de bronze\" class=\"wp-image-17658\" title=\"\" srcset=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/7b-1024x1024.jpg 1024w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/7b-980x980.jpg 980w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/7b-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Grau<\/strong><\/td><td><strong>Composi\u00e7\u00e3o<\/strong><\/td><td><strong>Usos comuns<\/strong><\/td><\/tr><tr><td><strong>C36000<\/strong><\/td><td>61 a 65% Cobre + 35 a 39% Zinco<\/td><td>Ele oferece a m\u00e1xima usinabilidade para tipos delicados de pe\u00e7as eletr\u00f4nicas, encanamentos e acess\u00f3rios.<\/td><\/tr><tr><td><strong>C46400<\/strong><\/td><td>57% de cobre + 40% de zinco + 2 a 4% de estanho<\/td><td>Com v\u00e1rios recursos t\u00e1teis, de alta resist\u00eancia e resistentes \u00e0 corros\u00e3o, ele \u00e9 simplesmente mais uma op\u00e7\u00e3o em acess\u00f3rios mar\u00edtimos.<\/td><\/tr><tr><td><strong>C26800<\/strong><\/td><td>68% Cobre + 32% Zinco<\/td><td>Alguns dos componentes el\u00e9tricos e itens de decora\u00e7\u00e3o precisam ser moldados. Isso afeta o desempenho.<\/td><\/tr><tr><td><strong>C38500<\/strong><\/td><td>60% Cobre + 40% Zinco<\/td><td>O cobre e o zinco formam uma camada estrat\u00e9gica de metal. A finalidade \u00e9 tornar mais resistentes os encanamentos, as pe\u00e7as el\u00e9tricas e as ferragens de constru\u00e7\u00e3o.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Bronze_Alloy_Grades_and_Uses\"><\/span><a><\/a>Classes e usos de ligas de bronze<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Grau<\/strong><strong><\/strong><\/td><td><strong>Composi\u00e7\u00e3o<\/strong><strong><\/strong><\/td><td><strong>Usos comuns<\/strong><strong><\/strong><\/td><\/tr><tr><td><strong>C93200<\/strong><strong><\/strong><\/td><td>88% cobre + 7 a 10% estanho<\/td><td>Essa liga protege relativamente os rolamentos, as buchas, as pe\u00e7as mar\u00edtimas e as engrenagens contra o desgaste.<\/td><\/tr><tr><td><strong>C51000<\/strong><strong><\/strong><\/td><td>95% Cobre + 5% Estanho<\/td><td>\u00c9 usado principalmente em molas, conectores el\u00e9tricos e maquin\u00e1rio industrial. Eles s\u00e3o mais delicados e precisam ser protegidos contra fadiga.<\/td><\/tr><tr><td><strong>C61400<\/strong><strong><\/strong><\/td><td>85% Cobre + 5 a 7% Estanho + 0,15% F\u00f3sforo<\/td><td>Essa classe minimiza a exposi\u00e7\u00e3o \u00e0 oxida\u00e7\u00e3o e ao desgaste em contatos el\u00e9tricos, molas e pe\u00e7as automotivas.<\/td><\/tr><tr><td><strong>C87850<\/strong><strong><\/strong><\/td><td>90% de cobre + 10% de estanho<\/td><td>A prote\u00e7\u00e3o e a dureza adequadas s\u00e3o essenciais para melhorar o desempenho e a vida \u00fatil de v\u00e1lvulas, bombas e pe\u00e7as mar\u00edtimas.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Applications_of_Copper_Brass_and_Bronze\"><\/span><a><\/a>Aplica\u00e7\u00f5es de cobre, lat\u00e3o e bronze<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Electrical_Wiring\"><\/span><a><\/a>1.   Fia\u00e7\u00e3o el\u00e9trica<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Caracter\u00edsticas como condutividade el\u00e9trica e t\u00e9rmica e resist\u00eancia \u00e0 corros\u00e3o s\u00e3o proporcionadas pelo cobre. Os produtos que s\u00e3o compat\u00edveis com o cobre s\u00e3o a fia\u00e7\u00e3o de resid\u00eancias, aparelhos eletr\u00f4nicos e instala\u00e7\u00f5es industriais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Plumbing_Systems\"><\/span><a><\/a>2.   Sistemas de encanamento<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O lat\u00e3o e o cobre revelariam esses aprimoramentos est\u00e9ticos, tornando os tubos e conex\u00f5es de \u00e1gua n\u00e3o apenas flex\u00edveis, mas tamb\u00e9m resistentes \u00e0 corros\u00e3o. J\u00e1 o cobre \u00e9 bom para proteger os canos contra a corros\u00e3o.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Marine_Industry\"><\/span><a><\/a>3.   Setor mar\u00edtimo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ao escolher entre bronze e cobre, o bronze desempenha um papel relativamente mais significativo, pois encontra diretamente a ferrugem nas bombas de \u00e1gua do mar e nas pe\u00e7as mar\u00edtimas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_Decorative_Items_and_Statues\"><\/span><a><\/a>4.   Itens decorativos e est\u00e1tuas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O cobre e o lat\u00e3o permitem que a membrana projete esculturas e monumentos externos com eleg\u00e2ncia, tanto em termos de apelo quanto de atratividade. Aqui, o bronze equilibra a resist\u00eancia e mant\u00e9m a durabilidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_Musical_Instruments\"><\/span><a><\/a>5.   Instrumentos musicais<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Uma boa qualidade de som \u00e9 extremamente necess\u00e1ria para itens musicais. Outra considera\u00e7\u00e3o importante nesses instrumentos \u00e9 o fator ac\u00fastico exclusivo, em que o lat\u00e3o \u00e9 a melhor op\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Are_copper_brass_and_bronze_are_sustainable_metals\"><\/span>O cobre, o lat\u00e3o e o bronze s\u00e3o metais sustent\u00e1veis?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Cobre, lat\u00e3o e bronze s\u00e3o metais sustent\u00e1veis com a finalidade de serem reciclados v\u00e1rias vezes. Os fabricantes podem absolutamente reutiliz\u00e1-los, reduzindo seu impacto ambiental.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sustainability_Benefits\"><\/span><a><\/a>Benef\u00edcios de sustentabilidade<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>Cobre<\/strong>: O cobre se tornou popular devido \u00e0 sua pureza e compatibilidade com a reciclagem. Alguns desses metais apresentam v\u00e1rias vantagens. Ele n\u00e3o perde suas propriedades. <a href=\"https:\/\/circulareconomy.europa.eu\/platform\/sites\/default\/files\/euric_metal_recycling_factsheet.pdf\" target=\"_blank\" rel=\"noopener\">A reciclagem do cobre reduz basicamente as emiss\u00f5es de di\u00f3xido de carbono em at\u00e9 65%.<\/a><\/p>\n\n\n\n<p><strong>Lat\u00e3o:<\/strong> O lat\u00e3o geralmente permite que o metal\u00fargico reduza o desperd\u00edcio. Ele inclui componentes reciclados de cobre e zinco. Assim, a reten\u00e7\u00e3o de <a href=\"https:\/\/www.copper.org\/choosebrass\/pdf\/brass-rod-a-poster-child-for-sustainability.php\" target=\"_blank\" rel=\"noopener\">95% do valor para sucata<\/a> garante uma produ\u00e7\u00e3o mais suave. \u00c9 nesse ponto que o lat\u00e3o economiza recursos e oferece ciclos de vida longos.<\/p>\n\n\n\n<p><strong>Bronze<\/strong>: A reciclagem de lat\u00e3o reduz a maior parte das poss\u00edveis pegadas de carbono logo nas instala\u00e7\u00f5es de fabrica\u00e7\u00e3o. Aqui reside a conserva\u00e7\u00e3o real das mat\u00e9rias-primas. A reciclagem do bronze mant\u00e9m a densidade com rela\u00e7\u00e3o ao desempenho aprimorado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_to_identify_copper_or_bronze_or_brass\"><\/span>Como identificar cobre, bronze ou lat\u00e3o?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Como identificar cobre, lat\u00e3o e bronze\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/YlNDAyy3rPs?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Identificar a diferen\u00e7a entre cobre, bronze e lat\u00e3o \u00e9 um dos est\u00e1gios de valida\u00e7\u00e3o mais elementares. Portanto, ser\u00e3o necess\u00e1rios testes simples, mas eficazes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Color_Differences\"><\/span><a><\/a>Diferen\u00e7as de cor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/8b-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/8b-1-1024x1024.jpg\" alt=\"colora\u00e7\u00e3o\" class=\"wp-image-17660\" title=\"\" srcset=\"https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/8b-1-1024x1024.jpg 1024w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/8b-1-980x980.jpg 980w, https:\/\/www.aludiecasting.com\/wp-content\/uploads\/2024\/11\/8b-1-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<p><strong>Cobre<\/strong>: Confirma que o metal tem uma tonalidade laranja-avermelhada com um brilho met\u00e1lico.<\/p>\n\n\n\n<p><strong>Bronze<\/strong>: Decida o quanto o metal se assemelha a um tom marrom avermelhado. Ele deve ser mais escuro que o cobre e ter tons dourados sutis.<\/p>\n\n\n\n<p><strong>Lat\u00e3o<\/strong>: Avalie se a liga tem uma tonalidade amarela brilhante ou se exibe uma cor semelhante \u00e0 do ouro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Scratch_and_Density_Test\"><\/span><a><\/a>Teste de arranh\u00f5es e densidade<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>Cobre<\/strong>: A suavidade do cobre traz confiabilidade ao processo de fabrica\u00e7\u00e3o. Ao mesmo tempo, essa liga pode ser arranhada facilmente.<\/p>\n\n\n\n<p><strong>Bronze<\/strong>: O bronze tamb\u00e9m pode ser arranhado, mas \u00e9 mais duro do que o cobre e o lat\u00e3o.<\/p>\n\n\n\n<p><strong>Lat\u00e3o<\/strong>: No debate entre cobre e lat\u00e3o, o lat\u00e3o vence em termos de resist\u00eancia a arranh\u00f5es melhor do que o cobre. Isso reflete a combina\u00e7\u00e3o de dureza e qualidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Magnetism\"><\/span><a><\/a>Magnetismo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Em uma linha de fabrica\u00e7\u00e3o de alto n\u00edvel, o cobre, o lat\u00e3o e o bronze n\u00e3o s\u00e3o magn\u00e9ticos. Cada um deles ocorre na forma de vazamento. Muitos fabricantes costumam usar ferramentas magn\u00e9ticas para identificar o cobre, o lat\u00e3o ou o bronze em rela\u00e7\u00e3o ao a\u00e7o ou ao ferro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclus\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Selecionando entre <a href=\"https:\/\/aludiecasting.com\/pt\/usinagem-cnc-de-latao\/\">lat\u00e3o<\/a>O uso de cobre, cobre ou bronze depende das necessidades de seu projeto. Isso requer um conhecimento de suas propriedades e usos. Cada um deles oferece excelente resist\u00eancia \u00e0 corros\u00e3o, baixo atrito, apelo abrasivo e caracter\u00edsticas condutoras de eletricidade. Isso \u00e9 necess\u00e1rio para aplica\u00e7\u00f5es funcionais e itens art\u00edsticos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"FAQs\"><\/span>Perguntas frequentes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li><strong>Como saber a diferen\u00e7a entre cobre e lat\u00e3o?<\/strong><\/li>\n<\/ol>\n\n\n\n<p>O cobre ganhou popularidade devido \u00e0 sua cor marrom-avermelhada. Ele \u00e9 mais pesado que o lat\u00e3o e desenvolve uma p\u00e1tina verde. Enquanto o lat\u00e3o \u00e9 basicamente amarelo-dourado, principalmente devido ao teor de zinco. Sua capacidade de resistir a manchas \u00e9 a variedade da matriz.&nbsp;<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>O que \u00e9 melhor, cobre ou lat\u00e3o?<\/strong><\/li>\n<\/ol>\n\n\n\n<p>O cobre \u00e9 adequado para fia\u00e7\u00e3o e encanamento, o que se correlaciona com a condutividade el\u00e9trica e a resist\u00eancia \u00e0 corros\u00e3o. Por outro lado, acess\u00f3rios, instrumentos musicais e itens de decora\u00e7\u00e3o dependem do lat\u00e3o devido \u00e0 sua for\u00e7a e apelo decorativo.&nbsp;<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>Por que o bronze \u00e9 mais cor de cobre do que o lat\u00e3o?<\/strong><\/li>\n<\/ol>\n\n\n\n<p>Porque o bronze cont\u00e9m uma propor\u00e7\u00e3o maior de cobre (80-90%) do que o lat\u00e3o (55-95%, dilu\u00eddo com zinco). O maior teor de cobre cria um tom de bronze avermelhado distinto no bronze. Mas o zinco d\u00e1 uma tonalidade amarelo-ouro.<\/p>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>Lat\u00e3o e bronze s\u00e3o a mesma coisa?<\/strong><\/li>\n<\/ol>\n\n\n\n<p>N\u00e3o, os suti\u00e3s s\u00e3o compostos de cobre e zinco, enquanto o bronze \u00e9 principalmente uma liga de cobre e estanho.<\/p>\n\n\n\n<ol start=\"5\" class=\"wp-block-list\">\n<li><strong>Que material devo evitar nas joias?<\/strong><\/li>\n<\/ol>\n\n\n\n<p>Evite metais de lat\u00e3o e bronze para joias. Eles causam rea\u00e7\u00f5es al\u00e9rgicas e podem manchar rapidamente. O cobre \u00e9 o melhor metal para joias dentre o lat\u00e3o e o bronze. Ele oferece alta maleabilidade e atributos hipoalerg\u00eanicos. Isso resiste \u00e0s rea\u00e7\u00f5es al\u00e9rgicas.<\/p>","protected":false},"excerpt":{"rendered":"<p>There are three basic difference between Brass, bronze and copper. Copper is pure metal. Brass and bronze are alloys. Brass is an alloy of copper. Bronze is an alloy of copper and tin. PropertyCopperBrassBronzeCompositionPure copperCopper + ZincCopper + TinColorReddish-brownGolden yellowDark brown to golden**Density (g\/cm\u00b3)8.968.4-8.737.4-8.9Melting Point (\u00b0C)1085900-940950-1050 Let&#8217;s compare their properties, uses, pros and cons, and [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17661,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-17651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aluminium-alloy-castings"],"_links":{"self":[{"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/posts\/17651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/comments?post=17651"}],"version-history":[{"count":0,"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/posts\/17651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/media\/17661"}],"wp:attachment":[{"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/media?parent=17651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/categories?post=17651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aludiecasting.com\/pt\/wp-json\/wp\/v2\/tags?post=17651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}